{"id":3764,"count":2,"description":"","link":"https:\/\/www.christinaschlegl.de\/en\/tag\/seerosenteich","name":"Seerosenteich","slug":"seerosenteich","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/tags\/3764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/posts?tags=3764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}