{"id":3522,"count":1,"description":"","link":"https:\/\/www.christinaschlegl.de\/en\/tag\/steg-32","name":"Steg 32","slug":"steg-32","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/tags\/3522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.christinaschlegl.de\/en\/wp-json\/wp\/v2\/posts?tags=3522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}